{"id":2459,"date":"2020-02-13T11:46:42","date_gmt":"2020-02-13T11:46:42","guid":{"rendered":"https:\/\/www.click-mallorca.com\/blog\/?p=2459"},"modified":"2025-03-11T17:19:04","modified_gmt":"2025-03-11T17:19:04","slug":"ruta-en-el-norte-de-mallorca","status":"publish","type":"post","link":"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/","title":{"rendered":"Ruta en el norte de Mallorca"},"content":{"rendered":"<p>Hoy os proponemos una ruta en el norte de Mallorca. En los t\u00e9rminos de Pollensa y Alcudia, los m\u00e1s septentrionales de la isla de Mallorca, se ubican las pen\u00ednsulas de Formentor y de la victoria, dos espacios naturales al abrigo de masivas urbanizaciones, que reservan panor\u00e1micas de excepcional atractivo. La cultura y el arte en la ciudad de Pollensa, la historia en la de Alcudia, la oferta tur\u00edstica y gastron\u00f3mica en sus puestos respectivos hacen de este recorrido, con final en el Parque Natural de S\u2019Albufera, un continuo solaz para\u00a0 el visitante.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2461 aligncenter\" src=\"https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/calvari-pollensa.jpg\" alt=\"pollensa\" width=\"833\" height=\"446\" srcset=\"https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/calvari-pollensa.jpg 1680w, https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/calvari-pollensa-300x161.jpg 300w, https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/calvari-pollensa-768x411.jpg 768w, https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/calvari-pollensa-1024x549.jpg 1024w\" sizes=\"auto, (max-width: 833px) 100vw, 833px\" \/><\/p>\n<h2><\/h2>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_72 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<label for=\"ez-toc-cssicon-toggle-item-6a04b8345a23f\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04b8345a23f\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/#pollenca\" title=\"Pollen\u00e7a\">Pollen\u00e7a<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/#-oratorio-del-roser-vell\" title=\"\u00a0Oratorio del Roser Vell\">\u00a0Oratorio del Roser Vell<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/#claustro-del-convento-de-santo-domingo-iglesia-de-nostra-senyora-del-roser-y-museo-de-pollenca\" title=\"Claustro del convento de Santo domingo, iglesia de Nostra Senyora\u00a0 del Roser y Museo de Pollen\u00e7a\">Claustro del convento de Santo domingo, iglesia de Nostra Senyora\u00a0 del Roser y Museo de Pollen\u00e7a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/#-parroquia-de-nostra-senyora-dels-angels\" title=\"\u00a0Parroquia de Nostra Senyora dels Angels\">\u00a0Parroquia de Nostra Senyora dels Angels<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/#el-puig-de-maria\" title=\"El Puig de Mar\u00eda\">El Puig de Mar\u00eda<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/#el-calvari\" title=\"El Calvari\">El Calvari<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/#cala-sant-vicenc\" title=\"Cala Sant Vicen\u00e7\">Cala Sant Vicen\u00e7<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/#peninsula-de-formentor\" title=\"Pen\u00ednsula de Formentor\">Pen\u00ednsula de Formentor<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/#port-de-pollenca\" title=\"Port de Pollen\u00e7a\">Port de Pollen\u00e7a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/#alcudia\" title=\"Alcudia\">Alcudia<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/#ciudad-romana-de-pollentia\" title=\"Ciudad romana de Pollentia\">Ciudad romana de Pollentia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/#teatro-romano\" title=\"Teatro romano\">Teatro romano<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/#murallas-porta-de-sara-porta-de-mallorca-y-vestido-de-sant-ferran\" title=\"Murallas, porta de Sara, Porta de Mallorca y vestido de Sant Ferran\">Murallas, porta de Sara, Porta de Mallorca y vestido de Sant Ferran<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/#museo-monografico-de-pollentia\" title=\"Museo monogr\u00e1fico de Pollentia\">Museo monogr\u00e1fico de Pollentia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/#iglesia-parroquial-y-capilla-del-santo-cristo\" title=\"Iglesia parroquial y capilla del Santo Cristo\">Iglesia parroquial y capilla del Santo Cristo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/#-oratorio-de-santa-aina\" title=\"\u00a0Oratorio de Santa Aina\">\u00a0Oratorio de Santa Aina<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/www.click-mallorca.com\/blog\/actividades\/paisaje\/ruta-en-el-norte-de-mallorca\/#port-dalcudia\" title=\"Port d\u2019Alc\u00fadia\">Port d\u2019Alc\u00fadia<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"pollenca\"><\/span><strong><u>Pollen\u00e7a<\/u><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Pollensa ha sido calificada con acierto como \u201cla ciutat del art\u201d. No quedar\u00e1 defraudado quien se acerque a ella con prop\u00f3sitos art\u00edsticos. La vida cultural pollensina ha sido desde siempre mascar\u00f3n de proa que ha hecho de la villa uno de los lugares m\u00e1s emblem\u00e1ticos, inquietos y cosmopolitas de Mallorca, guardando con celosa fidelidad la etimolog\u00eda de su top\u00f3nimo: la pujante, la poderosa. Es cierto aqu\u00ed el t\u00f3pico de la hospitalidad. No por casualidad much\u00edsimos artistas venidos de cualquier rinc\u00f3n del planeta han elegido Pollensa como lugar de residencia y de creaci\u00f3n. El visitante comprobar\u00e1 fehaciente mente el car\u00e1cter acogedor del pollens\u00edn , abierto y al mismo tiempo orgulloso de sus tradiciones, de lo que da buena prueba el entusiasmo de las diversas y ancestrales fiestas populares desparramadas a lo largo del a\u00f1o.<\/p>\n<p>Por descontado que una vez llegados a Pollensa, lo indispensable es abandonar inmediatamente el coche y disponerse a ejercitar el callejero de manera pausada y distendida para empezar esta ruta a pie en el norte de Mallorca. Si se viene de Palma el acceso l\u00f3gico es a trav\u00e9s de la carretera PM-220 aunque tambi\u00e9n puede hacerse por la menos transitada C-710, procedente de Lluc o por la propia PM- 220 pero desde Alcudia, tras bordear la bah\u00eda de Pollensa y atravesar el puerto. Destacaremos aqu\u00ed de forma sucinta todo aquello que resulta imprescindible de visitar, aunque la organizaci\u00f3n de los trayectos la dejamos en parte al arbitrio de cada cual.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"-oratorio-del-roser-vell\"><\/span><strong>\u00a0Oratorio del Roser Vell<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Situado a la entrada misma de Pollensa quiz\u00e1s deber\u00eda ser el primer punto de parada para quienes procedan por la carretera PM-220 proveniente de la C-713 que atraviesa la isla de sur a norte. Se deber\u00e1 tomar la primera desviaci\u00f3n a la izquierda nada m\u00e1s toparse con los indicadores que nos anuncian que hemos llegado a Pollensa, deteni\u00e9ndose poco despu\u00e9s (unos 200 m.)de adentrarse en el Carrer del Roser-vell. Se trata de un oratorio de comienzos del siglo XVI recientemente restaurado. Cuenta con un portal anexo, de \u00e9poca g\u00f3tica y estructura rom\u00e1nica, as\u00ed como un grupo escult\u00f3rico, fechado en la \u00e9poca de construcci\u00f3n del templo, conocido como Les Maries del Roser -vell.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17412 aligncenter\" src=\"https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2020\/02\/puig-de-maria-1.jpg\" alt=\"puig de maria\" width=\"2165\" height=\"1112\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"claustro-del-convento-de-santo-domingo-iglesia-de-nostra-senyora-del-roser-y-museo-de-pollenca\"><\/span><strong>Claustro del convento de Santo domingo, iglesia de Nostra Senyora\u00a0 del Roser y Museo de Pollen\u00e7a<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Se trata de edificaciones anexas en cuyos muros se celebran diferentes manifestaciones art\u00edsticas a lo largo de a\u00f1o. El claustro acoge durante los meses de julio, agosto y septiembre el muy renombrado Festival Internacional de M\u00fasica de Pollensa, cita imprescindible de mel\u00f3manos en las serenas noches estivales. Tambi\u00e9n en el se celebra, coincidiendo con las fiestas patronales de agosto el Certamen Internacional de Pintura y escultura, cuyas obras ganadoras pasan a engrosar el fondo de la colecci\u00f3n exhibida en el Museo de Pollensa, anexo al claustro, por cuyo interior se accede. Y las diferentes estancias de este, puede tambi\u00e9n disfrutarse con la contemplaci\u00f3n de diversas tablas del g\u00f3tico mallorqu\u00edn, entre las que destaca de la Mare de D\u00e9u dels Angels Musics, as\u00ed como valiosas piezas etnogr\u00e1ficas y lit\u00fargicas, en las que cabe remarcar la colecci\u00f3n de ollas mallorquinas del siglo XVII o las piezas de madera de car\u00e1cter religioso-funerario conocidas como Els Braus de la Punta. La iglesia de Nostra Senyora del Roser ha cogido las tres ediciones recientes del certamen Art Pollensa, dedicadas al arte aborigen australiano, arte budista tibetano y arte ind\u00edgena huichol, celebradas en el mes de agosto . Cuenta dicha iglesia con un retablo barroco de Joan A. Homs, una talla de la Verge del Roser-vell fechada en los siglos XIII y la sepultura del h\u00e9roe popular Joan Mas ( 1520 1607), en cuya hist\u00f3rica gesta se fundamenta la anual celebraci\u00f3n de la batalla entre moros y cristianos. Menci\u00f3n aparte merece el \u00f3rgano barroco del valenciano Luis navarro, construido en 1732 y restaurado en 1977 por el maestro alem\u00e1n Gerhard Grenzing.<\/p>\n<p>Frente a esas edificaciones, el paseante puede contemplar los jardines Joan March, con su muestra de plantas aut\u00f3ctonas, una pieza de artiller\u00eda que form\u00f3 parte desde el siglo XVII de la torre defensiva de Cala San Vicen\u00e7, la estatua dedicada a Joan Mas con los versos que le dedicara Costa i Llobera y la torre g\u00f3tica que preside el escenario, cuyo horario de visita se restringe a los martes, jueves y domingos de 10 a 12 de la ma\u00f1ana.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"-parroquia-de-nostra-senyora-dels-angels\"><\/span><strong>\u00a0Parroquia de Nostra Senyora dels Angels<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Situada junto a la plaza central (conocida como La Pla\u00e7a, donde hay mercado dominical), se trata de un templo dedicado a la patrona de la ciudad. Fue fundada por los templarios tras el reparto de la isla por los conquistadores catalanes. Cuenta con ornamentaci\u00f3n barroca, entre la que destaca el retablo fechado en 1754. El campanario se alza sobre lo que fuera una antigua torre defensiva del siglo XV. En su sacrist\u00eda se ver\u00e1n diferentes recuerdos del poeta y eclesi\u00e1stico Miquel Costa i Llobera.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"el-puig-de-maria\"><\/span><strong>El Puig de Mar\u00eda<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Esta es una de las m\u00e1s populares ruta en el norte de Mallorca. Si el Calvari flanquea la ciudad desde el norte, el Puig de Mar\u00eda lo hace desde su parte sur. Para llegar hasta el hasta el hemos de volver a la carretera PM-220 que circunda Pollensa y seguir las se\u00f1alizaciones situadas antes de entrar en el n\u00facleo urbanizado de la ciudad, emplazada en su falda. Aunque el acceso en coche casi hasta la cima es factible, conviene desaconsejarlo seriamente, dado que la carretera es muy estrecha, llena de baches y con tramos muy empinados. Se puede armar un foll\u00f3n considerable si se toman dos coches de frente sin espacio para maniobrar. Es mejor obrarse de paciencia y hacer la subida a pie. Desde su cima se puede contemplar una impresionante panor\u00e1mica de las zonas que abarca el presente itinerario. El santuario de la Mare de D\u00e9u del Puig data de finales del siglo XIV, predominando el estilo g\u00f3tico y destacando su refectorio. Conserva un camino empedrado del siglo XVII obra de los \u201cmargers\u201dmallorquines. A sus 333 m de altura puede accederse a pie en aproximadamente una hora.<\/p>\n<p>Su monasterio fue uno de los m\u00e1s importantes de la isla hasta que el Concilio de Trento impuso la clausura o el abandono del lugar. Hasta hace unos a\u00f1os era habitado por ermita\u00f1os, que lo hab\u00edan reocupado a partir de 1918. Cuenta con torre de defensa y murallas, lo que evidencia su otrora notable papel estrat\u00e9gico. El Puig de Mar\u00eda ha sido declarado \u00e1rea natural de especial inter\u00e9s. Su denso encinar cuenta con un sotobosque de gran riqueza bot\u00e1nica aut\u00f3ctona( cirerer de betlem, pa porc\u00ed, arbocera, xuclamel, aritja, roseta\u2026) Tanto en este como en la garriga existe tambi\u00e9n una amplia panoplia de fauna orn\u00edtica, destacando el busqueret de cap negre, el busqueret coa llarga, el trencapinyons, la p\u00e0ssera de pit vermell, la merla, el passaforad\u00ed y la cadernera, entre otras aves que har\u00e1n las delicias de los amantes de la ornitolog\u00eda.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"el-calvari\"><\/span><strong>El Calvari<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Junto al Ayuntamiento en el Carrer Jes\u00fas, comienza su escalinata flanqueada por cipreses y compuesta, uno por cada d\u00eda del a\u00f1o, por 365 escalones. Tomando aliento, el visitante no debe dejar pasar la ascensi\u00f3n hasta lo alto del mont\u00edculo, coronado por un oratorio de comienzos del siglo XIX que fue restaurado con talante neog\u00f3tico hace tres d\u00e9cadas. En \u00e9l se venera la imagen de la Mare de D\u00e9u del Peu de la Creu, fechada en el siglo XIII o XIV punto en esta escalinata se celebra cada Viernes Santo el impresionante desfile procesional denominado El\u00a0 Davallament, que congrega devotos y curiosos de toda la isla, as\u00ed como turistas atra\u00eddos por la tradici\u00f3n popular. Si se baja por la carretera, los estrechos y sinuosos carrer de les Creus i Gruat, que hacen aconsejable no utilizar el coche, se llegar\u00e1 al puente romano, monumento hist\u00f3rico- art\u00edstico, parte de la conducci\u00f3n de agua que abastec\u00eda a la vecina ciudad de Pollentia<\/p>\n<h2><span class=\"ez-toc-section\" id=\"cala-sant-vicenc\"><\/span><strong><u>Cala Sant Vicen\u00e7<\/u><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Saliendo de Pollen\u00e7a en direcci\u00f3n hacia el puerto por la PM 220 y transcurridos un par de kil\u00f3metros existe una desviaci\u00f3n a la izquierda por la que se accede a Cala Sant Vicen\u00e7. Al llegar a esta, a mano derecha pueden visitarse las cuevas prehist\u00f3ricas de car\u00e1cter funerario pertenecientes a la edad del bronce. Hay quien las considera como el mejor ejemplar de necr\u00f3polis pretalay\u00f3tica del Mediterr\u00e1neo occidental, destacando en este sentido la cueva n\u00famero 7. Su dataci\u00f3n se remonta hacia el 1500 antes de Cristo y han sido declaradas Patrimonio Art\u00edstico nacional.<\/p>\n<p>Las diversas caras que componen la cala Sant Vicen\u00e7 (Cala Barques, Cala Clara, Cala Molins, Cala Carb\u00f3\u2026) ofrecen unas aguas cristalinas y una amplia oferta de hoteles y apartamentos, as\u00ed como un conjunto de restaurantes especializados en platos marineros. Quienes acudan con la intenci\u00f3n de recorrer su entorno paisaj\u00edstico pueden dirigirse al Hotel Don Pedro y contactar con Mark Hamilton, gu\u00eda de monta\u00f1a que proporcionar\u00e1 la informaci\u00f3n que se precisen o bien telefonear a Klaus Himmermann 971 535 374. La espl\u00e9ndida vista, a la derecha en direcci\u00f3n al mar, del majestuoso Cavall Bernat, uno de los paisajes m\u00e1s reiteradamente pintados por innumerables artistas, bien merece la visita.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2464 aligncenter\" src=\"https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/peninsula-formentor.jpg\" alt=\"formentor\" width=\"800\" height=\"532\" srcset=\"https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/peninsula-formentor.jpg 800w, https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/peninsula-formentor-300x200.jpg 300w, https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/peninsula-formentor-768x511.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"peninsula-de-formentor\"><\/span><strong><u>Pen\u00ednsula de Formentor<\/u><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>De regreso a la PM-220, proseguimos hacia el Port de Pollen\u00e7a. Al poco de entrar en \u00e9l, antes de llegar al mar, una se\u00f1alizaci\u00f3n nos indica que debemos girar a la izquierda para tomar la carretera que conduce a Formentor. 9 kil\u00f3metros nos separan del hotel y la Playa, 20 de Cap Formentor. Quien desee hacer una excursi\u00f3n a pie (unos tres cuartos de hora) puede torcer a la izquierda desde la urbanizaci\u00f3n Cala B\u00f3quer y llegar a la cala virgen de igual nombre, tras pasar por la \u201cposessi\u00f3\u201d privada. A la izquierda queda ahora la sierra del Cavall Bernat, en cuya falda se encuentran notables construcciones talai\u00f3ticas, origen de Bocchoris, la ciudad pre-romana.<\/p>\n<p>Siguiendo carretera arriba (la PM-221) obra del ingeniero Parietti) pronto llegaremos a la creueta, con su famoso Mirador d\u2019es Colomer, as\u00ed llamado por el islote o farall\u00f3n tan y tan fotografiado que desde \u00e9l se divisa. Recomendamos que tras la parada obligada, el visitante tome ahora hacia la derecha en lugar de seguir adelante. Una carretera c\u00f3moda nos llevar\u00e1 hasta la Talaia d\u2019Abercuitx, desde donde se puede disfrutar deuna de las mejores vistas sobre las dos bah\u00edas (Pollen\u00e7a y Alcudia) y sobre la costa norte de la Pen\u00ednsula de Formentor. La Talaia (as\u00ed es conocida en la zona) fue construida a finales del S. XVI y serv\u00eda como torre de se\u00f1ales ante las incursiones turcas. En la guerra civil se edificaron\u00a0 unas horribles construcciones en forma de b\u00fanker\u00a0 que afean la zona por su estado de abandono y que alg\u00fan d\u00eda deber\u00e1n desaparecer en beneficio del entorno.<\/p>\n<p>Volviendo atr\u00e1s regresamos a la PM-221 y nos dirigimos hacia la Playa de Formentor, con sus pinos casi al borde del mar, polo de atracci\u00f3n de miles de visitantes en la temporada de calor. Hay parking de pago y chiringuitos acondicionados para comer. Al final de la carretera que bordea la playa se encuentra el Hotel Formentor, \u00fanico y emblem\u00e1tico. Si en lugar de detenernos en la playa hemos optado por dirigirnos hacia la izquierda una vez llegados al cruce, 11 kms. Nos separan del Cap Formentor, el punto m\u00e1s septentrional de\u00a0 la isla de Mallorca, con su colosal faro. De camino, a mano izquierda dejaremos las Cases de les Velles, lugar de culto para muchos entusiastas de Miquel Costa i Llobera, con el homenaje anual en su recuerdo. Numerosos miradores habilitados para la yoma de fotograf\u00edas se encuentran al borde de la carretera. A la izquierda tambi\u00e9n se puede puede toar el camino que baja hasta Cala Figuera y disfrutar de aguas cristalinas. A la derecha queda Cala Murta, uno de los escenarios naturales m\u00e1s cantados por los versos de Costa i Llobera.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2465 aligncenter\" src=\"https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/pollensa-llenaire.jpg\" alt=\"port pollensa\" width=\"883\" height=\"447\" srcset=\"https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/pollensa-llenaire.jpg 1699w, https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/pollensa-llenaire-300x152.jpg 300w, https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/pollensa-llenaire-768x389.jpg 768w, https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/pollensa-llenaire-1024x519.jpg 1024w\" sizes=\"auto, (max-width: 883px) 100vw, 883px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"port-de-pollenca\"><\/span><strong><u>Port de Pollen\u00e7a<\/u><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Abandonar el coche y caminar pl\u00e1cidamente por el paseo peatonal que bordea entre pinos la bah\u00eda sigue siendo una delicia, en especial al atardecer o en las noches veraniegas. All\u00ed se hayan hoteles pioneros con todo el sabor de los inicios del turismo como el Illa d\u2019Or, el Miramar o el Sis pins. El Museo Anglada Camarasa, consagrado al famoso pintor vanguardista, se halla en fase de traslado a palma. Desde el paseo peatonal se puede observar la punta de la avanzada y en ellas las ruinas de Sa\u00a0 Fortalesa un conjunto arquitect\u00f3nico declarado monumento hist\u00f3rico- art\u00edstico, que cuenta con doscientas obras en su mayor\u00eda del escultor Josep de Creeft y que el Ayuntamiento de Pollensa pretende reacondicionar y convertir en lugar de uso p\u00fablico. De momento, el paso se haya restringido pues para acceder a Sa Fortalesa debe atravesarse por zona militar. Desde el Port de Pollensa pueden realizarse excursiones en barca diariamente por la bah\u00eda o con destino a Formentor, adem\u00e1s de beneficiarse de su amplia oferta deportiva, desde el buceo hasta el windsurfing, pasando por las clases de vela.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2466 aligncenter\" src=\"https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/alcudia-xperience-bus-3.png\" alt=\"alcudia\" width=\"871\" height=\"402\" srcset=\"https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/alcudia-xperience-bus-3.png 871w, https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/alcudia-xperience-bus-3-300x138.png 300w, https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/alcudia-xperience-bus-3-768x354.png 768w\" sizes=\"auto, (max-width: 871px) 100vw, 871px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"alcudia\"><\/span><strong><u>Alcudia<\/u><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Su bien ganada declaraci\u00f3n como Conjunto Hist\u00f3rico Art\u00edstico por la Direcci\u00f3n General de Bellas artes, hace de Alcudia un lugar ideal para quienes deseen rastrear las huellas dejadas por nuestros antepasados. A la riqueza de la cultura talay\u00f3tica de su t\u00e9rmino (Biniatria, SA Figuera roja ,Cana Menescala, Oriolet, Claper des Gegant, son Siurana de dalt, Don sim\u00f3\u2026) une los vestigios de aquellas civilizaciones que se disputaron su privilegiado en clave. El visitante que acceda por la carretera PM-222 que circunda la ciudad encontrar\u00e1 aparcamiento f\u00e1cil en el Passeig de la Mare de D\u00e9u de la Victoria, poco antes de la desviaci\u00f3n a la derecha hacia el Puerto, salvo los martes y domingos, cuando se celebra el concurrido mercado hortofrut\u00edcola y artesanal de 6 a 13. Proponemos que el recorrido comienza extramuros de la ciudad, en los restos de la ciudad romana para adentrarse luego por las estrechas y laber\u00ednticas callejuelas de Alcudia.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"ciudad-romana-de-pollentia\"><\/span><strong>Ciudad romana de Pollentia<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Los restos de la ciudad fundada por Quinto Cecilio Metelo en el a\u00f1o 123 antes de cristo. Se hallan en la parte derecha de la carretera que bordea Alcudia. Los cipreses situados en la curva en cuya otra orilla se halla la iglesia parroquial servir\u00e1n de pista para dar con ellos. Los \u00edmprobos e \u00a0impagables trabajos desarrollados por el arque\u00f3logo William L Bryant y por la Fundaci\u00f3n que lleva su nombre han hecho posible el dejar al descubierto la ret\u00edcula urbana de Pollentia, evidenciando el esplendor que debi\u00f3 alcanzar. Su localizaci\u00f3n prosigue en l\u00ednea recta hacia el mar desde la l\u00ednea de Alcudia, en paralelo a la carretera que lleva al puerto a unos 200 metros de la iglesia parroquial quedan restos de la muralla que rodea la ciudad romana, cuyos momentos m\u00e1s brillantes se produjeron en los tres primeros siglos de nuestra era. Las incursiones y saqueos de los v\u00e1ndalos a mediados del s.V conllevaron su desaparici\u00f3n, traes una etapa de decadencia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2467 aligncenter\" src=\"https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/alcudia-xperience-bus-2.png\" alt=\"ciudad romana alcudia\" width=\"872\" height=\"398\" srcset=\"https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/alcudia-xperience-bus-2.png 872w, https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/alcudia-xperience-bus-2-300x137.png 300w, https:\/\/www.click-mallorca.com\/blog\/wp-content\/uploads\/2019\/12\/alcudia-xperience-bus-2-768x351.png 768w\" sizes=\"auto, (max-width: 872px) 100vw, 872px\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"teatro-romano\"><\/span><strong>Teatro romano<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Siguiendo el camino interior en direcci\u00f3n al mar se puede llegar hasta el. Otra entrada se produce por la carretera PM-222 que une Alcudia y el puerto, a mano derecha justo al salir de la ciudad. Con el fondo de la bah\u00eda de Alcudia, fue construido en el siglo I d.c. De planta griega, con\u201d Orchestra\u201d de 5 metros de radio y grader\u00edo tallado en semic\u00edrculo. Se trata de uno de los teatros romanos de menores dimensiones conocidos en Espa\u00f1a, pese a lo cual contaba con una capacidad aproximada para unas 2000 personas. Cuando se abandon\u00f3, la zona de la escena fue utilizada como lugar de sepultura, probablemente durante la alta Edad media. Coincidiendo con las fiestas patronales de la Mare de D\u00e9u d\u2019Agost se celebra aqu\u00ed la Mostra de Teatre, que en sus dos ediciones ha incluido obras de Goldoni, Moliere y autores mallorquines.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"murallas-porta-de-sara-porta-de-mallorca-y-vestido-de-sant-ferran\"><\/span><strong>Murallas, porta de Sara, Porta de Mallorca y vestido de Sant Ferran<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Comenzar\u00e1 ahora el recorrido intramuros de Alcudia esta nueva ruta en el norte de Mallorca. Las murallas de la ciudad fueron ordenadas construir por el rey Jaime II en 1298, continuando sus sucesores Sancho I y Jaime III. Pedro III el Ceremonioso concluir\u00eda en 1362 la fortificaci\u00f3n. Desde este primer circuito resta en la puerta de Xara (en la plaza Carlos quinto, frente al monumento que recuerda la fidelidad de Alcudia al emperador durante la revuelta de los agermanats\u201d) y la Porta de Mallorca, ambas \u00a0declaradas Monumento nacional.<\/p>\n<p>Un segundo circuito amurallado se llev\u00f3 a cabo durante los reinados de Felipe III y Felipe IV, acab\u00e1ndose 1960. De esta resta un fragmento (el Basti\u00f3 de Sant Ferran )que rodea la plaza de toros, ubicada en el extremo de la ciudad opuesto a la iglesia parroquial, accediendo se tomando hacia la izquierda cuando se llega desde la carretera de Palma y se topa con la muralla, camino del Barcar\u00e9s.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"museo-monografico-de-pollentia\"><\/span><strong>Museo monogr\u00e1fico de Pollentia<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>\u00a0<\/strong>Para el visitante que ya haya recogido los restos de Pollentia, el Museo le permitir\u00e1 comprobar los vestigios encontrados a lo largo de las diferentes excavaciones, con sus 2000 piezas inventariadas desde 1926, desde ajuares funerarios, \u00e1nforas, monedas, ornamentos, l\u00e1pidas hasta vasijas de bronce y cer\u00e1mica, estatuas de m\u00e1rmol blanco, esculturas o mosaicos. Situado en el antiguo edificio del Hospital de Alcudia, frente a la iglesia parroquial, entre sus piezas m\u00e1s valiosas se halla la cabeza de una ni\u00f1a esculpida en bronce, con cabello ondulado y trenza recogida a modo de corona.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"iglesia-parroquial-y-capilla-del-santo-cristo\"><\/span><strong>Iglesia parroquial y capilla del Santo Cristo<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>\u00a0<\/strong>\u00a0Se hace inmediatamente visible desde la carretera y hasta ahora nos ha servido de orientaci\u00f3n para nuestro recorrido. Es de estilo neog\u00f3tico y tuvo que ser totalmente reconstruida entre 1882 y 1893 tras venirse abajo la que fuera mandada construir por Jaime II. De esta se conserva la Capilla del Santo cristo, edificio anexo construido en el \u00faltimo tercio del siglo XVII, de estilo renacentista. Cuenta con un retablo barroco sobre el altar.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h3><span class=\"ez-toc-section\" id=\"-oratorio-de-santa-aina\"><\/span><strong>\u00a0Oratorio de Santa Aina<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Salimos nuevamente del recinto de la ciudad para tomar el conocido como Cam\u00ed del cementiri, paralelo a las ruinas de Pollentia por su izquierda. A unos 500 metros de Alcudia el visitante se encontrar\u00e1 con un oratorio edificado en el siglo XIII, uno de los escasos vestigios arquitect\u00f3nicos de los primeros a\u00f1os de la invasi\u00f3n catalano-aragonesa. Se trata de un edificio de un s\u00f3lo cuerpo de planta baja y tejado en dos vertientes sostenidas por tres arcos de estilo g\u00f3tico. Sobre su entrada, una imagen de la Virgen de la Bona Nova, tallada en piedra.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"port-dalcudia\"><\/span><strong><u>Port d\u2019Alc\u00fadia<\/u><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>En el Port d&#8217;Alcudia tenemos otra de las ruta en el norte de Mallorca. Siguiendo por el Cam\u00ed del cementiri hacia el mar se llega al Port d\u2019Alc\u00fadia. Tambi\u00e9n puede hacerse por la PM-222. En cualquiera de los dos casos, al llegar al paseo que bordea el mar, a la izquierda la carretera se encamina hacia el canad\u00e1, a la derecha hacia S\u2019Albufera y Can Picafort en direcci\u00f3n harta. Vale la pena acercarse hasta el canad\u00e1, no solo por sus excelentes restaurantes, sino tambi\u00e9n por contemplar la isla Alcanada y su faro una vez atravesada la urbanizaci\u00f3n. Antes de entrar en la carretera que nos conduce hacia esta, a la derecha se deja el muelle pesquero, d\u00f3nde es f\u00e1cil encontrar gran n\u00famero de aficionados a la pesca con ca\u00f1a o carrete. De vuelta al puerto, d\u00f3nde se puede comer excelente pescado, en la zona del Club N\u00e1utico se encontrar\u00e1 a los \u201cMestres d\u2019aixa\u201d en plena labor artesanal de construcci\u00f3n de embarcaciones de pesca, los t\u00edpicos \u201clla\u00fcts\u201d mallorquines. Hay salidas en barco diarias hasta el cap Menorca y hasta Formentor.<\/p>\n<p>Siguiendo por la carretera de Art\u00e0 en cuyo n\u00famero 68 se halla la Oficina de Informaci\u00f3n tur\u00edstica, cerrada solo los domingos, al llegar a la calle Pedro m\u00e1s y Reus ( poco antes del lago esperanza ) el visitante puede girar a la derecha y atravesar la urbanizaci\u00f3n Belleveu para llegar hasta la Cova de San Mart\u00ed. Se trata de una construcci\u00f3n paleo-cristiana cuyo culto fue restablecido tras la conquista catalana en el siglo XIII. Cuenta con dos capillas con altar, las de Sant Mart\u00ed i Sant jordi, ambas situadas a 12 metros de profundidad con acceso a trav\u00e9s de pronunciadas escaleras el camino prosigue hasta el Puig de Sant mart\u00ed, anexo al Puig de Son Fe, ambos declarados \u00e1rea natural de especial inter\u00e9s<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hoy os proponemos una ruta en el norte de Mallorca. En los t\u00e9rminos de Pollensa y Alcudia, los m\u00e1s septentrionales de la isla de Mallorca, se ubican las pen\u00ednsulas de Formentor y de la&#46;&#46;&#46;<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":2463,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-2459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paisaje"],"lang":"es","translations":{"es":2459},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.click-mallorca.com\/blog\/wp-json\/wp\/v2\/posts\/2459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.click-mallorca.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.click-mallorca.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.click-mallorca.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.click-mallorca.com\/blog\/wp-json\/wp\/v2\/comments?post=2459"}],"version-history":[{"count":7,"href":"https:\/\/www.click-mallorca.com\/blog\/wp-json\/wp\/v2\/posts\/2459\/revisions"}],"predecessor-version":[{"id":17413,"href":"https:\/\/www.click-mallorca.com\/blog\/wp-json\/wp\/v2\/posts\/2459\/revisions\/17413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.click-mallorca.com\/blog\/wp-json\/wp\/v2\/media\/2463"}],"wp:attachment":[{"href":"https:\/\/www.click-mallorca.com\/blog\/wp-json\/wp\/v2\/media?parent=2459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.click-mallorca.com\/blog\/wp-json\/wp\/v2\/categories?post=2459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.click-mallorca.com\/blog\/wp-json\/wp\/v2\/tags?post=2459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}